{"id":8467,"date":"2026-02-02T08:34:20","date_gmt":"2026-02-02T07:34:20","guid":{"rendered":"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/"},"modified":"2026-02-02T08:34:20","modified_gmt":"2026-02-02T07:34:20","slug":"estudio-biblico-en-friedberg-23","status":"publish","type":"tribe_events","link":"http:\/\/ichha.org\/de\/event\/estudio-biblico-en-friedberg-23\/","title":{"rendered":"Estudio b\u00edblico en Friedberg"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2662,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[144],"class_list":["post-8467","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-espanol","cat_espanol"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estudio b\u00edblico en Friedberg | ICHHA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/ichha.org\/de\/event\/estudio-biblico-en-friedberg-23\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:locale:alternate\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio b\u00edblico en Friedberg | ICHHA\" \/>\n<meta property=\"og:url\" content=\"http:\/\/ichha.org\/de\/event\/estudio-biblico-en-friedberg-23\/\" \/>\n<meta property=\"og:site_name\" content=\"ICHHA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iglesiahispanaichha\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/\",\"url\":\"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/\",\"name\":\"Estudio b\u00edblico en Friedberg | ICHHA\",\"isPartOf\":{\"@id\":\"http:\/\/ichha.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ichha.org\/wp-content\/uploads\/2019\/03\/Bibelkreis.png\",\"datePublished\":\"2026-02-02T07:34:20+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#primaryimage\",\"url\":\"http:\/\/ichha.org\/wp-content\/uploads\/2019\/03\/Bibelkreis.png\",\"contentUrl\":\"http:\/\/ichha.org\/wp-content\/uploads\/2019\/03\/Bibelkreis.png\",\"width\":210,\"height\":210},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/ichha.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"http:\/\/ichha.org\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Estudio b\u00edblico en Friedberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/ichha.org\/#website\",\"url\":\"http:\/\/ichha.org\/\",\"name\":\"ICHHA\",\"description\":\"Compartiendo el amor de Dios\",\"publisher\":{\"@id\":\"http:\/\/ichha.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/ichha.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/ichha.org\/#organization\",\"name\":\"Iglesia de la comunidad hispano hablante de Alemania\",\"url\":\"http:\/\/ichha.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"http:\/\/ichha.org\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ichha.org\/wp-content\/uploads\/2018\/11\/ICHHA-Titel.png\",\"contentUrl\":\"http:\/\/ichha.org\/wp-content\/uploads\/2018\/11\/ICHHA-Titel.png\",\"width\":750,\"height\":750,\"caption\":\"Iglesia de la comunidad hispano hablante de Alemania\"},\"image\":{\"@id\":\"http:\/\/ichha.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/iglesiahispanaichha\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio b\u00edblico en Friedberg | ICHHA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/ichha.org\/de\/event\/estudio-biblico-en-friedberg-23\/","og_locale":"de_DE","og_type":"article","og_title":"Estudio b\u00edblico en Friedberg | ICHHA","og_url":"http:\/\/ichha.org\/de\/event\/estudio-biblico-en-friedberg-23\/","og_site_name":"ICHHA","article_publisher":"https:\/\/www.facebook.com\/iglesiahispanaichha\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/","url":"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/","name":"Estudio b\u00edblico en Friedberg | ICHHA","isPartOf":{"@id":"http:\/\/ichha.org\/#website"},"primaryImageOfPage":{"@id":"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#primaryimage"},"image":{"@id":"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#primaryimage"},"thumbnailUrl":"http:\/\/ichha.org\/wp-content\/uploads\/2019\/03\/Bibelkreis.png","datePublished":"2026-02-02T07:34:20+00:00","breadcrumb":{"@id":"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#primaryimage","url":"http:\/\/ichha.org\/wp-content\/uploads\/2019\/03\/Bibelkreis.png","contentUrl":"http:\/\/ichha.org\/wp-content\/uploads\/2019\/03\/Bibelkreis.png","width":210,"height":210},{"@type":"BreadcrumbList","@id":"http:\/\/ichha.org\/event\/estudio-biblico-en-friedberg-23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/ichha.org\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"http:\/\/ichha.org\/events\/"},{"@type":"ListItem","position":3,"name":"Estudio b\u00edblico en Friedberg"}]},{"@type":"WebSite","@id":"http:\/\/ichha.org\/#website","url":"http:\/\/ichha.org\/","name":"ICHHA","description":"Compartiendo el amor de Dios","publisher":{"@id":"http:\/\/ichha.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/ichha.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"http:\/\/ichha.org\/#organization","name":"Iglesia de la comunidad hispano hablante de Alemania","url":"http:\/\/ichha.org\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"http:\/\/ichha.org\/#\/schema\/logo\/image\/","url":"http:\/\/ichha.org\/wp-content\/uploads\/2018\/11\/ICHHA-Titel.png","contentUrl":"http:\/\/ichha.org\/wp-content\/uploads\/2018\/11\/ICHHA-Titel.png","width":750,"height":750,"caption":"Iglesia de la comunidad hispano hablante de Alemania"},"image":{"@id":"http:\/\/ichha.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iglesiahispanaichha\/"]}]}},"_links":{"self":[{"href":"http:\/\/ichha.org\/de\/wp-json\/wp\/v2\/tribe_events\/8467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ichha.org\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"http:\/\/ichha.org\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"http:\/\/ichha.org\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"http:\/\/ichha.org\/de\/wp-json\/wp\/v2\/tribe_events\/8467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ichha.org\/de\/wp-json\/wp\/v2\/media\/2662"}],"wp:attachment":[{"href":"http:\/\/ichha.org\/de\/wp-json\/wp\/v2\/media?parent=8467"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ichha.org\/de\/wp-json\/wp\/v2\/tags?post=8467"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"http:\/\/ichha.org\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=8467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}